{"id":1257,"date":"2023-10-09T14:20:21","date_gmt":"2023-10-09T14:20:21","guid":{"rendered":"https:\/\/allin.online\/eolaire-taic\/"},"modified":"2023-12-20T10:55:39","modified_gmt":"2023-12-20T10:55:39","slug":"eolaire-taic","status":"publish","type":"page","link":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/","title":{"rendered":"E\u00f2laire taic"},"content":{"rendered":"\n<div class=\"wp-block-ace-content flex content-content bg_white padding indent one-column\"><div class=\"content_wrapper\">\n<div class=\"wp-block-ace-intro content-intro\"><p><br>Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.<\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Thoir an aire, chan eil am fiosrachadh mu bhuidhnean sa phasgan seo ri fhaighinn ach sa Bheurla aig an \u00e0m seo. Tha sinn an-dr\u00e0sta a\u2019 coimhead ri d\u00f2ighean anns an aithnich sinn nas fhe\u00e0rr buidhnean a tha ag obair anns a\u2019 Gh\u00e0idhlig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gus ballrachd a ghabhail sa phasgan mar sholaraiche, feuch an l\u00econ thu am foirm aig bonn na duilleige.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tha a h-uile fiosrachadh ga thoirt seachad leis an t-solaraiche agus chan eil e air a dhearbhadh leis an sgioba All In.<\/p>\n<\/div><\/div>\n\n\n\t<div class=\"org_list bg_grey indent padding padding--half\" >\n\t\t\t<h2>Find a Support Organisation<\/h2>\n\t\t\t<button id=\"open_filters\" aria-expanded=\"false\" aria-controls=\"filter_list\">Filter buidhnean<\/button>\n\t\t\t<div class=\"flex two_column\">\n\t\t\t\t<aside class=\"sidebar filter_list\" id=\"filter_list\">\n\t\t\t\t\t<a href=\"#response\" class=\"screen-reader-text\">Air adhart gu toraidhean<\/a>\n\t\t\t\t\t<h3>Filter organisations by:<\/h3>\n\t\t\t\t\t    <form id=\"filter\" class=\"filter\">\n                        <details open>\n                    <summary><span class=\"screen-reader-text\">S\u00ecolaich buidhnean le<\/span>Support type<\/summary>\n                        <div class = \"panel\">\n                            <ul>\n                                                                   <li><input type=\"checkbox\" id=\"beurla-le-taic-shoidhnidh\" name=\"accessibility[]\" value=\"beurla-le-taic-shoidhnidh\" data-name=\"Beurla le Taic Shoidhnidh\" \/><label for=beurla-le-taic-shoidhnidh>Beurla le Taic Shoidhnidh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"bunait-eolais\" name=\"accessibility[]\" value=\"bunait-eolais\" data-name=\"Bunait E\u00f2lais\" \/><label for=bunait-eolais>Bunait E\u00f2lais<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"canan-soidhnidh-bhreatainn-bsl\" name=\"accessibility[]\" value=\"canan-soidhnidh-bhreatainn-bsl\" data-name=\"C\u00e0nan-soidhnidh Bhreatainn (BSL)\" \/><label for=canan-soidhnidh-bhreatainn-bsl>C\u00e0nan-soidhnidh Bhreatainn (BSL)<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"canan-soidhnidh-na-h-eirinn\" name=\"accessibility[]\" value=\"canan-soidhnidh-na-h-eirinn\" data-name=\"C\u00e0nan-soidhnidh na h-\u00c8irinn\" \/><label for=canan-soidhnidh-na-h-eirinn>C\u00e0nan-soidhnidh na h-\u00c8irinn<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"co-chomhairle\" name=\"accessibility[]\" value=\"co-chomhairle\" data-name=\"Co-chomhairle\" \/><label for=co-chomhairle>Co-chomhairle<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"coidseadh\" name=\"accessibility[]\" value=\"coidseadh\" data-name=\"Coidseadh\" \/><label for=coidseadh>Coidseadh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"comhairleachadh\" name=\"accessibility[]\" value=\"comhairleachadh\" data-name=\"Comhairleachadh\" \/><label for=comhairleachadh>Comhairleachadh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"deuchainn-cleachdaidh\" name=\"accessibility[]\" value=\"deuchainn-cleachdaidh\" data-name=\"Deuchainn Cleachdaidh\" \/><label for=deuchainn-cleachdaidh>Deuchainn Cleachdaidh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"easy-read\" name=\"accessibility[]\" value=\"easy-read\" data-name=\"Easy Read\" \/><label for=easy-read>Easy Read<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"fo-thiotailean\" name=\"accessibility[]\" value=\"fo-thiotailean\" data-name=\"Fo-thiotailean\" \/><label for=fo-thiotailean>Fo-thiotailean<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"makaton\" name=\"accessibility[]\" value=\"makaton\" data-name=\"Makaton\" \/><label for=makaton>Makaton<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"marketing\" name=\"accessibility[]\" value=\"marketing\" data-name=\"Marketing\" \/><label for=marketing>Marketing<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"mineachadh-claisneachd\" name=\"accessibility[]\" value=\"mineachadh-claisneachd\" data-name=\"M\u00ecneachadh Claisneachd\" \/><label for=mineachadh-claisneachd>M\u00ecneachadh Claisneachd<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"sgrudadh-ruigsinneachd\" name=\"accessibility[]\" value=\"sgrudadh-ruigsinneachd\" data-name=\"Sgr\u00f9dadh Ruigsinneachd\" \/><label for=sgrudadh-ruigsinneachd>Sgr\u00f9dadh Ruigsinneachd<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"software\" name=\"accessibility[]\" value=\"software\" data-name=\"Software\" \/><label for=software>Software<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"streaming-livestreaming\" name=\"accessibility[]\" value=\"streaming-livestreaming\" data-name=\"Streaming\/Livestreaming\" \/><label for=streaming-livestreaming>Streaming\/Livestreaming<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"taic-aghaidh-ri-aghaidh-loidhne-thaic\" name=\"accessibility[]\" value=\"taic-aghaidh-ri-aghaidh-loidhne-thaic\" data-name=\"Taic Aghaidh-ri-Aghaidh \/ L\u00f2idhne Thaic\" \/><label for=taic-aghaidh-ri-aghaidh-loidhne-thaic>Taic Aghaidh-ri-Aghaidh \/ L\u00f2idhne Thaic<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"treanadh\" name=\"accessibility[]\" value=\"treanadh\" data-name=\"Tr\u00e8anadh\" \/><label for=treanadh>Tr\u00e8anadh<\/label><\/li>\n                                                            <\/ul>\n                        <\/div>\n                <\/details>\n                            <details open>\n                    <summary><span class=\"screen-reader-text\">S\u00ecolaich buidhnean le<\/span>Artforms supported<\/summary>\n                        <div class = \"panel\">\n                            <ul>\n                                                                   <li><input type=\"checkbox\" id=\"ceaird\" name=\"art_form[]\" value=\"ceaird\" data-name=\"Ce\u00e0ird\" \/><label for=ceaird>Ce\u00e0ird<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"ceol\" name=\"art_form[]\" value=\"ceol\" data-name=\"Ce\u00f2l\" \/><label for=ceol>Ce\u00f2l<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"dannsa\" name=\"art_form[]\" value=\"dannsa\" data-name=\"Dannsa\" \/><label for=dannsa>Dannsa<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"ealain-cleasachd\" name=\"art_form[]\" value=\"ealain-cleasachd\" data-name=\"Ealain Cleasachd\" \/><label for=ealain-cleasachd>Ealain Cleasachd<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"ealain-measgaichte\" name=\"art_form[]\" value=\"ealain-measgaichte\" data-name=\"Ealain Measgaichte\" \/><label for=ealain-measgaichte>Ealain Measgaichte<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"ealainean-leirsinneach\" name=\"art_form[]\" value=\"ealainean-leirsinneach\" data-name=\"Ealainean L\u00e8irsinneach\" \/><label for=ealainean-leirsinneach>Ealainean L\u00e8irsinneach<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"feisean\" name=\"art_form[]\" value=\"feisean\" data-name=\"F\u00e8isean\" \/><label for=feisean>F\u00e8isean<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"fiolm-sgrin\" name=\"art_form[]\" value=\"fiolm-sgrin\" data-name=\"Fiolm\/Sgr\u00ecn\" \/><label for=fiolm-sgrin>Fiolm\/Sgr\u00ecn<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"leabharlannan\" name=\"art_form[]\" value=\"leabharlannan\" data-name=\"Leabharlannan\" \/><label for=leabharlannan>Leabharlannan<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"litreachas\" name=\"art_form[]\" value=\"litreachas\" data-name=\"Litreachas\" \/><label for=litreachas>Litreachas<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"taighean-tasgaidh\" name=\"art_form[]\" value=\"taighean-tasgaidh\" data-name=\"Taighean-tasgaidh\" \/><label for=taighean-tasgaidh>Taighean-tasgaidh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"teatar\" name=\"art_form[]\" value=\"teatar\" data-name=\"T\u00e8atar\" \/><label for=teatar>T\u00e8atar<\/label><\/li>\n                                                            <\/ul>\n                        <\/div>\n                <\/details>\n                            <details open>\n                    <summary><span class=\"screen-reader-text\">S\u00ecolaich buidhnean le<\/span>Operates in<\/summary>\n                        <div class = \"panel\">\n                            <ul>\n                                                                   <li><input type=\"checkbox\" id=\"a-chuimrigh\" name=\"location[]\" value=\"a-chuimrigh\" data-name=\"A\u2019 Chuimrigh\" \/><label for=a-chuimrigh>A\u2019 Chuimrigh<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"air-loidhne\" name=\"location[]\" value=\"air-loidhne\" data-name=\"Air loidhne\" \/><label for=air-loidhne>Air loidhne<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"alba\" name=\"location[]\" value=\"alba\" data-name=\"Alba\" \/><label for=alba>Alba<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"eirinn-a-tuath\" name=\"location[]\" value=\"eirinn-a-tuath\" data-name=\"\u00c8irinn a Tuath\" \/><label for=eirinn-a-tuath>\u00c8irinn a Tuath<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"ireland\" name=\"location[]\" value=\"ireland\" data-name=\"Ireland\" \/><label for=ireland>Ireland<\/label><\/li>\n                                                                    <li><input type=\"checkbox\" id=\"sasainn\" name=\"location[]\" value=\"sasainn\" data-name=\"Sasainn\" \/><label for=sasainn>Sasainn<\/label><\/li>\n                                                            <\/ul>\n                        <\/div>\n                <\/details>\n                    <input type=\"reset\" value=\"Cl\u00ecor s\u00ecolanan\" class=\"button decorative reset\" \/>\n    <\/form>\n\t\t\t\t\t<a href=\"#response\" class=\"screen-reader-text\">Air adhart gu toraidhean<\/a>\n\t\t\t\t<\/aside>\n\t\t\t\t<div class=\"content content-directory\">\n\t\t\t\t\t<div class=\"flex current_filters hide\">\n\t\t\t\t\t\t<p>a\u2019 sealltainn thoraidhean air an s\u00ecoladh le<\/p>\n\t\t\t\t\t\t<ul id=\"current_filters\" aria-live=\"polite\"><\/ul>\t\t\t\t\t\t<button id=\"clear\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\">\n  <path id=\"close\" d=\"M31.332,14.478l-1.146-1.146-7.854,7.854-7.854-7.854-1.146,1.146,7.854,7.854-7.854,7.854,1.146,1.146,7.854-7.854,7.854,7.854,1.146-1.146-7.854-7.854Z\" transform=\"translate(-13.332 -13.332)\" fill=\"#fff\" class=\"has_white\" \/>\n<\/svg>\nCl\u00ecor s\u00ecolanan uile<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"flex flex_33\" id=\"response\" data-action=\"https:\/\/allin.online\/wp-json\/ace\/v1\/filter_support_organisations\" aria-live=\"polite\">\n\t\t\t\t\t\t<div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2024\/01\/Accessible-by-Design-Logo.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2024\/01\/Accessible-by-Design-Logo.png 500w, https:\/\/allin.online\/wp-content\/uploads\/2024\/01\/Accessible-by-Design-Logo-300x300.png 300w, https:\/\/allin.online\/wp-content\/uploads\/2024\/01\/Accessible-by-Design-Logo-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/accessible-by-design\/\">\n    <p class=\"h3\">Accessible by Design<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"156\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/actionspace.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/actionspace.jpg 320w, https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/actionspace-300x146.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/actionspace\/\">\n    <p class=\"h3\">ActionSpace<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"2070\" height=\"2070\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali.jpeg 2070w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-300x300.jpeg 300w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-1024x1024.jpeg 1024w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-150x150.jpeg 150w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-768x768.jpeg 768w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-1536x1536.jpeg 1536w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/Anjali-2048x2048.jpeg 2048w\" sizes=\"auto, (max-width: 2070px) 100vw, 2070px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/anjali-dance-company\/\">\n    <p class=\"h3\">Anjali Dance Company<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"218\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/AiE-Core-yellow-over-off-black-Copy.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/AiE-Core-yellow-over-off-black-Copy.jpg 533w, https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/AiE-Core-yellow-over-off-black-Copy-300x123.jpg 300w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/attitude-is-everything\/\">\n    <p class=\"h3\">Attitude is Everything<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"479\" height=\"396\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/BOP-portrait-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/BOP-portrait-1.png 479w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/BOP-portrait-1-300x248.png 300w\" sizes=\"auto, (max-width: 479px) 100vw, 479px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/birds-of-paradise-theatre-company\/\">\n    <p class=\"h3\">Birds of Paradise Theatre Company<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/1649324861148.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/1649324861148.jpg 200w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/1649324861148-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/creu-cymru\/\">\n    <p class=\"h3\">Creu Cymru<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"355\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg 446w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers-300x239.jpg 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/deaf-hearing-trailblazers-cic\/\">\n    <p class=\"h3\">Deaf &amp; Hearing Trailblazers CIC<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"794\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DCN_logo_Dark-Centred_CMYK-resize.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DCN_logo_Dark-Centred_CMYK-resize.png 1000w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DCN_logo_Dark-Centred_CMYK-resize-300x238.png 300w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DCN_logo_Dark-Centred_CMYK-resize-768x610.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/digital-culture-network\/\">\n    <p class=\"h3\">Digital Culture Network<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item support_organisation_item bg_white\">\n    <picture class=\"featured-img alt-block\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1230\" height=\"445\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DAC-logo-colour-RGB.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DAC-logo-colour-RGB.png 1230w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DAC-logo-colour-RGB-300x109.png 300w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DAC-logo-colour-RGB-1024x370.png 1024w, https:\/\/allin.online\/wp-content\/uploads\/2023\/10\/DAC-logo-colour-RGB-768x278.png 768w\" sizes=\"auto, (max-width: 1230px) 100vw, 1230px\" \/>        \n    <\/picture>\n    <a href=\"https:\/\/allin.online\/gd-gb\/support_organisation\/disability-arts-cymru\/\">\n    <p class=\"h3\">Disability Arts Cymru<\/p>\n    <p><\/p>\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31.832\" height=\"24\" viewBox=\"0 0 31.832 24\">\n  <path id=\"arrow\" d=\"M33.728,24.848l-10.2-10.2a1.773,1.773,0,1,0-2.508,2.508l7.189,7.189H4.272a1.772,1.772,0,0,0,0,3.545H28.178L21.022,35.08a1.755,1.755,0,0,0,0,2.508,1.827,1.827,0,0,0,1.271.536,1.747,1.747,0,0,0,1.271-.536L33.8,27.355a1.827,1.827,0,0,0,.536-1.271,2.283,2.283,0,0,0-.6-1.237Z\" transform=\"translate(-2.499 -14.123)\" fill=\"#472961\"\/>\n<\/svg>\n    <\/a>\n<\/div><div class=\"flex_item flex_placeholder\"><\/div><nav aria-label=\"Tagh duilleag nan toraidhean\"><ol class=\"pagination\"><li class=\"page-num\"><span aria-current=\"page\" class=\"page-numbers current\"><span class=\"screen-reader-text\">Duilleag <\/span>1<span class=\"screen-reader-text\"> \u00e0 4<\/span><\/span><\/li><li class=\"page-num\"><a class=\"page-numbers\" href=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/?paged=2\"><span class=\"screen-reader-text\">Duilleag <\/span>2<span class=\"screen-reader-text\"> \u00e0 4<\/span><\/a><\/li><li class=\"page-num\"><a class=\"page-numbers\" href=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/?paged=3\"><span class=\"screen-reader-text\">Duilleag <\/span>3<span class=\"screen-reader-text\"> \u00e0 4<\/span><\/a><\/li><li class=\"page-num\"><a class=\"page-numbers\" href=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/?paged=4\"><span class=\"screen-reader-text\">Duilleag <\/span>4<span class=\"screen-reader-text\"> \u00e0 4<\/span><\/a><\/li><li class=\"page-num\"><a class=\"next page-numbers\" href=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/?paged=2\"><span class=\"screen-reader-text\">Ath dhuilleag<\/span><span aria-hidden=\"true\">&raquo;<\/span><\/a><\/li><\/ol><\/nav>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n\n\n<div class=\"wp-block-ace-register-your-interest register-form bg-primary-primary_sub indent padding\" id=\"express_your_interest\"><h2>Cuir do Bhuidheann Taic ris<\/h2><p>A bheil thu a\u2019 riochdachadh buidheann neo an e neach-obrach saor-thoileach a th\u2019 annad a tha a\u2019 toirt taic do bhuidhnean cruthachail is cultarach gus ruigsinneachd nas fhe\u00e0rr a thabhann do dhaoine ciorramach agus dhaibhsan aig a bheil feumalachdan ruigsinneachd?<br><br>Ma tha thu airson a dhol dhan e\u00f2laire againn, l\u00econ a-steach am fiosrachadh agad gu h-\u00ecosal agus bidh sinn ann an conaltradh nuair a dh\u2019 fhosglas sinn an cl\u00e0r airson cl\u00e0raidhean \u00f9ra nas fhaide air adhart sa bhliadhna.<\/p>        <div id=\"form_response\">        <\/div>\n        <form method=\"POST\" id=\"signupform\" class=\"register_form\">\n            <input type=\"hidden\" name=\"action\" value=\"register_form\">\n            <input type=\"hidden\" name=\"form\" value=\"support_organisation\">\n            <div class=\"label_group\">\n                <label for=\"organisation_name\">Ainm na buidhne<span aria-hidden=\"true\">*<\/span><\/label>\n                <input type=\"text\"  name=\"organisation_name\" id=\"organisation_name\" aria-required=\"true\">\n            <\/div>\n            <div class=\"label_group\">\n                <label for=\"email\">Se\u00f2ladh puist-d<span aria-hidden=\"true\">*<\/span><\/label>\n                <input type=\"text\" name=\"email\" id=\"email\" aria-required=\"true\">\n            <\/div>\n            <div class=\"label_group\">\n                <label for=\"organisation_url\">URL na buidhne<span aria-hidden=\"true\">*<\/span><\/label>\n                <textarea name=\"organisation_url\" id=\"organisation_url\" aria-required=\"true\"><\/textarea>\n            <\/div>\n            <div class=\"label_group\">\n                <label for=\"add_info\">Fiosrachadh sam bith a Bharrachd<\/label>\n                <textarea name=\"add_info\" id=\"add_info\"><\/textarea>\n            <\/div>\n            <div class=\"label_group checkbox_container\">\n                <input type=\"checkbox\" name=\"consent\" id=\"consent\" aria-required=\"true\" data-error_message=\"To express your interest you need to agree to receive emails from us.\" >\n                <label for=\"consent\" class=\"smaller\">Tha mi ag aontachadh puist-d fhaighinn.<span aria-hidden=\"true\">*<\/span><\/label>\n            <\/div>\n            <input type=\"text\" name=\"require\" placeholder=\"This is bot protection. Don't fill in if you are human\" id=\"hp\">\n            <input type=\"submit\" class=\"button decorative\" id=\"submit\" value=\"Cuir a-steach\" >\n            <p class=\"small\" aria-hidden=\"true\">* Raon a tha a dh\u00ecth<\/p>\n        <\/form> \n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":1270,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"bsl_video":false,"register_block":true,"footnotes":""},"class_list":["post-1257","page","type-page","status-publish","hentry"],"acf":{"enable_signapse":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E\u00f2laire taic - All In<\/title>\n<meta name=\"description\" content=\"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E\u00f2laire taic - All In\" \/>\n<meta property=\"og:description\" content=\"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/\" \/>\n<meta property=\"og:site_name\" content=\"All In\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T10:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/All-In_OG-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/eolaire-taic\\\/\",\"url\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/eolaire-taic\\\/\",\"name\":\"E\u00f2laire taic - All In\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#website\"},\"datePublished\":\"2023-10-09T14:20:21+00:00\",\"dateModified\":\"2023-12-20T10:55:39+00:00\",\"description\":\"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/eolaire-taic\\\/#breadcrumb\"},\"inLanguage\":\"gd-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/eolaire-taic\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/eolaire-taic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Duilleag-dhachaigh\",\"item\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All In airson na Roinne\",\"item\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/all-in-airson-na-roinne\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"E\u00f2laire taic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#website\",\"url\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/\",\"name\":\"All in\",\"description\":\"Tha f\u00e0ilte air a h-uile duine\",\"publisher\":{\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gd-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#organization\",\"name\":\"All in\",\"url\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gd-GB\",\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/696x696.png\",\"contentUrl\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/696x696.png\",\"width\":696,\"height\":696,\"caption\":\"All in\"},\"image\":{\"@id\":\"https:\\\/\\\/allin.online\\\/gd-gb\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E\u00f2laire taic - All In","description":"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/","og_locale":"en_US","og_type":"article","og_title":"E\u00f2laire taic - All In","og_description":"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.","og_url":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/","og_site_name":"All In","article_modified_time":"2023-12-20T10:55:39+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/All-In_OG-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/","url":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/","name":"E\u00f2laire taic - All In","isPartOf":{"@id":"https:\/\/allin.online\/gd-gb\/#website"},"datePublished":"2023-10-09T14:20:21+00:00","dateModified":"2023-12-20T10:55:39+00:00","description":"Cleachd am pasgan againn gus taic fhaighinn bho luchd-comhairle, luchd-obrach neo-cheangailte agus buidhnean ruigsinneachd bho air feadh na RA.","breadcrumb":{"@id":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/#breadcrumb"},"inLanguage":"gd-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/eolaire-taic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Duilleag-dhachaigh","item":"https:\/\/allin.online\/gd-gb\/"},{"@type":"ListItem","position":2,"name":"All In airson na Roinne","item":"https:\/\/allin.online\/gd-gb\/all-in-airson-na-roinne\/"},{"@type":"ListItem","position":3,"name":"E\u00f2laire taic"}]},{"@type":"WebSite","@id":"https:\/\/allin.online\/gd-gb\/#website","url":"https:\/\/allin.online\/gd-gb\/","name":"All in","description":"Tha f\u00e0ilte air a h-uile duine","publisher":{"@id":"https:\/\/allin.online\/gd-gb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allin.online\/gd-gb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gd-GB"},{"@type":"Organization","@id":"https:\/\/allin.online\/gd-gb\/#organization","name":"All in","url":"https:\/\/allin.online\/gd-gb\/","logo":{"@type":"ImageObject","inLanguage":"gd-GB","@id":"https:\/\/allin.online\/gd-gb\/#\/schema\/logo\/image\/","url":"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/696x696.png","contentUrl":"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/696x696.png","width":696,"height":696,"caption":"All in"},"image":{"@id":"https:\/\/allin.online\/gd-gb\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/pages\/1257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/comments?post=1257"}],"version-history":[{"count":6,"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/pages\/1257\/revisions"}],"predecessor-version":[{"id":1374,"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/pages\/1257\/revisions\/1374"}],"up":[{"embeddable":true,"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/pages\/1270"}],"wp:attachment":[{"href":"https:\/\/allin.online\/gd-gb\/wp-json\/wp\/v2\/media?parent=1257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}