{"id":1433,"date":"2023-12-18T14:07:37","date_gmt":"2023-12-18T14:07:37","guid":{"rendered":"https:\/\/allin.online\/support_organisation\/deaf-hearing-trailblazers-cic\/"},"modified":"2024-11-06T14:39:46","modified_gmt":"2024-11-06T14:39:46","slug":"deaf-hearing-trailblazers-cic","status":"publish","type":"support_organisation","link":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/","title":{"rendered":"Deaf &amp; Hearing Trailblazers CIC"},"content":{"rendered":"\n<div class=\"wp-block-ace-content-support-organisation-wrapper content-wrapper\">\n<div class=\"wp-block-ace-content-support-organisation flex content-content two-column margins bg_white indent\">\n<div class=\"wp-block-ace-content-blocks border-top\"><div class =\"logo--org featured_image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"239\" src=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers-300x239.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers-300x239.jpg 300w, https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg 446w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\n\n<p class=\"wp-block-paragraph\">Deaf &amp; Hearing Trailblazers is the UK&#8217;s only dedicated training company bringing deaf and hearing people together to provide personal and professional development training.<br>We also provide bespoke consultancy support to help you evaluate, assess, and implement effective inclusive practices within your organisation.<\/p>\n<h3>Support Type<\/h3><ul class=\"cats\"><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=capsiynau\" class=\"cat\">Capsiynau<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=hyfforddiant\" class=\"cat\">Hyfforddiant<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=hyfforddiant-cy\" class=\"cat\">Hyfforddiant<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=iaith-arwyddion-prydain\" class=\"cat\">Iaith Arwyddion Prydain<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=mentora\" class=\"cat\">Mentora<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=profi-defnyddioldeb\" class=\"cat\">Profi Defnyddioldeb<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=saesneg-a-chymorth-iaith-arwyddion\" class=\"cat\">Saesneg \u00e2 Chymorth Iaith Arwyddion<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=sylfaen-wybodaeth\" class=\"cat\">Sylfaen Wybodaeth<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?accessibility[]=ymgynghoriaeth\" class=\"cat\">Ymgynghoriaeth<\/a><\/li><\/ul><h3>Artforms supported<\/h3><ul class=\"cats\"><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=amgueddfeydd\" class=\"cat\">Amgueddfeydd<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=celfyddydau-cyfun\" class=\"cat\">Celfyddydau Cyfun<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=celfyddydau-gweledol\" class=\"cat\">Celfyddydau Gweledol<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=crefft\" class=\"cat\">Crefft<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=ffilm-sgrin\" class=\"cat\">Ffilm\/Sgrin<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=gwyliau\" class=\"cat\">Gwyliau<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=llenyddiaeth\" class=\"cat\">Llenyddiaeth<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=llyfrgelloedd\" class=\"cat\">Llyfrgelloedd<\/a><\/li><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?art_form[]=theatr\" class=\"cat\">Theatr<\/a><\/li><\/ul><h3>Operates in<\/h3><ul class=\"cats\"><li><a href=\"https:\/\/allin.online\/cy\/\/all-in-for-the-sector\/support-organisations\/?location[]=lloegr\" class=\"cat\">Lloegr<\/a><\/li><\/ul><\/div>\n\n\n\n<aside class=\"wp-block-ace-organisation-sidebar border-top\"><dl>\n<dt class=\"wp-block-ace-website website\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32.001\" height=\"32\"><path fill=\"#472961\" d=\"M16 32a15.893 15.893 0 0 0 15.854-18.046v-.012a15.9 15.9 0 0 0-2.969-7.39 1.427 1.427 0 0 0-.135-.179 15.94 15.94 0 0 0-25.5 0 1.407 1.407 0 0 0-.138.184 15.9 15.9 0 0 0-2.967 7.387v.012A15.894 15.894 0 0 0 16 32ZM4.986 8.953c1.415.31 2.865.536 4.321.712a34.072 34.072 0 0 0-.524 4.447 52.316 52.316 0 0 1-4.812-.758c-.251-.052-.5-.115-.749-.169a13.007 13.007 0 0 1 1.764-4.232Zm23.791 4.231c-.254.056-.5.119-.758.172a52.251 52.251 0 0 1-4.8.755 34.087 34.087 0 0 0-.524-4.448c1.456-.176 2.9-.4 4.321-.712a13.008 13.008 0 0 1 1.763 4.231Zm-.431 7.128c-.578.146-1.158.292-1.737.421a45.217 45.217 0 0 1-3.75.637 35 35 0 0 0 .393-4.336c1.808-.2 3.608-.461 5.359-.83.16-.033.316-.074.475-.108a12.972 12.972 0 0 1-.739 4.214ZM16 29.091c-1 0-2.255-1.612-3.162-4.444 1.032.056 2.082.094 3.162.094s2.13-.038 3.162-.094c-.906 2.832-2.161 4.444-3.162 4.444Zm4.326-14.7a59.474 59.474 0 0 1-8.651 0 30.583 30.583 0 0 1 .515-4.442c1.233.087 2.5.147 3.81.147s2.581-.059 3.81-.147a30.54 30.54 0 0 1 .515 4.44Zm.012 2.915a31.219 31.219 0 0 1-.457 4.377 55.43 55.43 0 0 1-7.762 0 31.219 31.219 0 0 1-.457-4.377c1.409.1 2.834.165 4.338.165s2.933-.065 4.338-.165ZM22.004 6.82a18.068 18.068 0 0 0-1.17-2.976 13.142 13.142 0 0 1 4.035 2.554q-1.415.256-2.865.419Zm-2.936.267a52.944 52.944 0 0 1-6.136 0c.9-2.659 2.1-4.176 3.068-4.176s2.17 1.516 3.068 4.176Zm-9.072-.266q-1.45-.164-2.865-.42a13.138 13.138 0 0 1 4.035-2.554 18.035 18.035 0 0 0-1.17 2.974Zm-6.615 9.381c1.762.371 3.566.635 5.367.833a35 35 0 0 0 .393 4.335 44.763 44.763 0 0 1-3.746-.637 66.885 66.885 0 0 1-1.741-.421 12.987 12.987 0 0 1-.739-4.215c.155.033.311.074.466.105Zm2.055 7.5c1.376.282 2.824.506 4.324.678a19.167 19.167 0 0 0 1.406 3.779 13.156 13.156 0 0 1-5.732-4.46Zm15.398 4.454a19.167 19.167 0 0 0 1.406-3.779c1.5-.172 2.947-.4 4.324-.678a13.148 13.148 0 0 1-5.73 4.457Z\"><\/path><\/svg>Website<\/dt><dd><a href=\"https:\/\/www.dhtrailblazers.co.uk\" rel=\"noopener\">https:\/\/www.dhtrailblazers.co.uk<\/a><\/dd>\n<\/dl><\/aside>\n<\/div><div class=\"back_to padding indent bg_white\"><a href=\"https:\/\/allin.online\/cy\/all-in-ar-gyfer-y-sector\/dod-o-hyd-i-sefydliad-cymorth\/\" class=\"back_arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21.222\" height=\"16\"><path fill=\"#472961\" d=\"m.401 7.15 6.8-6.8a1.182 1.182 0 0 1 1.672 1.672L4.081 6.815h15.96a1.182 1.182 0 0 1 0 2.363H4.101l4.771 4.793a1.17 1.17 0 0 1 0 1.672 1.218 1.218 0 0 1-.847.357 1.165 1.165 0 0 1-.847-.357L.357 8.822a1.218 1.218 0 0 1-.356-.845 1.522 1.522 0 0 1 .4-.825Z\" data-name=\"back arrow\"><\/path><\/svg>Back to the directory<\/a><\/div>\n\n\n\n<div class=\"wp-block-ace-register-your-interest register-form bg-primary-primary_sub indent padding\" id=\"express_your_interest\"><h2>Stay in touch<\/h2><p>Be the first to hear about latest updates, news, and opportunities from the UK Access Scheme.<\/p>        <div id=\"form_response\" class=\"\" aria-live=\"polite\">        <\/div>\n        <form method=\"POST\" id=\"signupform\" class=\"register_form\">\n            <input type=\"hidden\" name=\"action\" value=\"register_form\">\n            <input type=\"hidden\" name=\"form\" value=\"sector_individual\">\n                            <div class=\"label_group compressed\">\n                    <label for=\"first_name\">Enw Cyntaf<span aria-hidden=\"true\">*<\/span><\/label>\n                    <input type=\"text\" name=\"first_name\" id=\"first_name\" aria-required=\"true\">\n                <\/div>\n                <div class=\"label_group compressed\">\n                    <label for=\"last_name\">Cyfenw<span aria-hidden=\"true\">*<\/span><\/label>\n                    <input type=\"text\" name=\"last_name\" id=\"last_name\" aria-required=\"true\">\n                <\/div>\n                <div class=\"label_group\">\n                    <label for=\"email\">Cyfeiriad E-bost<span aria-hidden=\"true\">*<\/span><\/label>\n                    <input type=\"text\" name=\"email\" id=\"email\" aria-required=\"true\">\n                <\/div>\n                        <div class=\"label_group compressed checkbox_container\">\n                <input id=\"sector\" type=\"checkbox\" name=\"sector\" value=\"sector\">\n                <label for=\"sector\">Rydw i\u2019n gweithio yn y sector creadigol a diwylliannol <\/label>\n            <\/div>\n            <div class=\"label_group compressed checkbox_container\">\n                <input id=\"disabled\" type=\"checkbox\" name=\"disabled\" value=\"disabled\">\n                <label for=\"disabled\">Rydw i\u2019n berson sydd \u00e2 gofynion mynediad <\/label>\n            <\/div>\n            <div class=\"label_group compressed checkbox_container\">\n                <input id=\"carer\" type=\"checkbox\" name=\"carer\" value=\"carer\">\n                <label for=\"carer\">Rwy&#8217;n ofalwr neu&#8217;n eiriolwr i rywun sydd \u00e2 gofynion mynediad<\/label>\n            <\/div>\n            <div class=\"label_group checkbox_container\">\n                <input type=\"checkbox\" name=\"consent\" id=\"consent\" aria-required=\"true\" data-error_message=\"To express your interest you need to agree to receive emails from us.\" >\n                <label for=\"consent\" class=\"smaller\">Rydw i\u2019n cytuno i dderbyn negeseuon e-bost<span aria-hidden=\"true\">*<\/span><\/label>\n            <\/div>\n            <input type=\"text\" name=\"require\" placeholder=\"This is bot protection. Don't fill in if you are human\" id=\"hp\">\n            <input type=\"submit\" class=\"button decorative\" id=\"submit\" value=\"Cyflwyno\" >\n            <p class=\"small\" aria-hidden=\"true\">*maes gofynnol<\/p>\n        <\/form> \n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1369,"template":"","accessibility":[60,61,67,59,65,68,66,64,62],"art_form":[92,85,96,86,89,88,91,90,95],"location":[97],"class_list":["post-1433","support_organisation","type-support_organisation","status-publish","has-post-thumbnail","hentry","accessibility-capsiynau","accessibility-hyfforddiant","accessibility-hyfforddiant-cy","accessibility-iaith-arwyddion-prydain","accessibility-mentora","accessibility-profi-defnyddioldeb","accessibility-saesneg-a-chymorth-iaith-arwyddion","accessibility-sylfaen-wybodaeth","accessibility-ymgynghoriaeth","art_form-amgueddfeydd","art_form-celfyddydau-cyfun","art_form-celfyddydau-gweledol","art_form-crefft","art_form-ffilm-sgrin","art_form-gwyliau","art_form-llenyddiaeth","art_form-llyfrgelloedd","art_form-theatr","location-lloegr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deaf &amp; Hearing Trailblazers CIC - All In<\/title>\n<meta name=\"description\" content=\"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/\" \/>\n<meta property=\"og:locale\" content=\"cy_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deaf &amp; Hearing Trailblazers CIC - All In\" \/>\n<meta property=\"og:description\" content=\"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/\" \/>\n<meta property=\"og:site_name\" content=\"All In\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T14:39:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"446\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/\",\"url\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/\",\"name\":\"Deaf &amp; Hearing Trailblazers CIC - All In\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1.DH-Trailblazers.jpg\",\"datePublished\":\"2023-12-18T14:07:37+00:00\",\"dateModified\":\"2024-11-06T14:39:46+00:00\",\"description\":\"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/#breadcrumb\"},\"inLanguage\":\"cy-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cy-GB\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1.DH-Trailblazers.jpg\",\"contentUrl\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/1.DH-Trailblazers.jpg\",\"width\":446,\"height\":355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/sefydliad_cymorth\\\/deaf-hearing-trailblazers-cic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hafan\",\"item\":\"https:\\\/\\\/allin.online\\\/cy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deaf &amp; Hearing Trailblazers CIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#website\",\"url\":\"https:\\\/\\\/allin.online\\\/cy\\\/\",\"name\":\"All in\",\"description\":\"Croeso i bawb\",\"publisher\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/allin.online\\\/cy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cy-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#organization\",\"name\":\"All in\",\"url\":\"https:\\\/\\\/allin.online\\\/cy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cy-GB\",\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/696x696.png\",\"contentUrl\":\"https:\\\/\\\/allin.online\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/696x696.png\",\"width\":696,\"height\":696,\"caption\":\"All in\"},\"image\":{\"@id\":\"https:\\\/\\\/allin.online\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deaf &amp; Hearing Trailblazers CIC - All In","description":"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/","og_locale":"cy_GB","og_type":"article","og_title":"Deaf &amp; Hearing Trailblazers CIC - All In","og_description":"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.","og_url":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/","og_site_name":"All In","article_modified_time":"2024-11-06T14:39:46+00:00","og_image":[{"width":446,"height":355,"url":"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/","url":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/","name":"Deaf &amp; Hearing Trailblazers CIC - All In","isPartOf":{"@id":"https:\/\/allin.online\/cy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/#primaryimage"},"image":{"@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/#primaryimage"},"thumbnailUrl":"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg","datePublished":"2023-12-18T14:07:37+00:00","dateModified":"2024-11-06T14:39:46+00:00","description":"Use the directory to find support from accessibility consultants, freelancers, and organisations from around the UK.","breadcrumb":{"@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/#breadcrumb"},"inLanguage":"cy-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/"]}]},{"@type":"ImageObject","inLanguage":"cy-GB","@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/#primaryimage","url":"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg","contentUrl":"https:\/\/allin.online\/wp-content\/uploads\/2023\/12\/1.DH-Trailblazers.jpg","width":446,"height":355},{"@type":"BreadcrumbList","@id":"https:\/\/allin.online\/cy\/sefydliad_cymorth\/deaf-hearing-trailblazers-cic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hafan","item":"https:\/\/allin.online\/cy\/"},{"@type":"ListItem","position":2,"name":"Deaf &amp; Hearing Trailblazers CIC"}]},{"@type":"WebSite","@id":"https:\/\/allin.online\/cy\/#website","url":"https:\/\/allin.online\/cy\/","name":"All in","description":"Croeso i bawb","publisher":{"@id":"https:\/\/allin.online\/cy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allin.online\/cy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cy-GB"},{"@type":"Organization","@id":"https:\/\/allin.online\/cy\/#organization","name":"All in","url":"https:\/\/allin.online\/cy\/","logo":{"@type":"ImageObject","inLanguage":"cy-GB","@id":"https:\/\/allin.online\/cy\/#\/schema\/logo\/image\/","url":"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/696x696.png","contentUrl":"https:\/\/allin.online\/wp-content\/uploads\/2023\/11\/696x696.png","width":696,"height":696,"caption":"All in"},"image":{"@id":"https:\/\/allin.online\/cy\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/support_organisation\/1433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/support_organisation"}],"about":[{"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/types\/support_organisation"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/media\/1369"}],"wp:attachment":[{"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"accessibility","embeddable":true,"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/accessibility?post=1433"},{"taxonomy":"art_form","embeddable":true,"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/art_form?post=1433"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/allin.online\/cy\/wp-json\/wp\/v2\/location?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}